{"id":3,"date":"2023-07-09T20:49:22","date_gmt":"2023-07-09T23:49:22","guid":{"rendered":"http:\/\/tcltech.com.br\/?page_id=3"},"modified":"2026-01-08T21:30:37","modified_gmt":"2026-01-09T00:30:37","slug":"politica-de-privacidade","status":"publish","type":"page","link":"https:\/\/tcltech.com.br\/index.php\/politica-de-privacidade\/","title":{"rendered":"Pol\u00edtica de privacidade"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Quem sou<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sou a TCL Tech. O endere\u00e7o do site \u00e9: https:\/\/tcltech.com.br.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Coment\u00e1rios<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Quando os visitantes deixam coment\u00e1rios no site, coletamos os dados mostrados no formul\u00e1rio de coment\u00e1rios, al\u00e9m do endere\u00e7o de IP e de dados do navegador do visitante, para auxiliar na detec\u00e7\u00e3o de spam.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma sequ\u00eancia anonimizada de caracteres criada a partir do seu e-mail (tamb\u00e9m chamada de hash) poder\u00e1 ser enviada para o Gravatar para verificar se voc\u00ea usa o servi\u00e7o. A pol\u00edtica de privacidade do Gravatar est\u00e1 dispon\u00edvel aqui: https:\/\/automattic.com\/privacy\/. Depois da aprova\u00e7\u00e3o do seu coment\u00e1rio, a foto do seu perfil fica vis\u00edvel publicamente junto de seu coment\u00e1rio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">M\u00eddia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea envia imagens para o site, evite enviar as que contenham dados de localiza\u00e7\u00e3o incorporados (EXIF GPS). Visitantes podem baixar estas imagens do site e extrair delas seus dados de localiza\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cookies<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ao deixar um coment\u00e1rio no site, voc\u00ea poder\u00e1 optar por salvar seu nome, e-mail e site nos cookies. Isso visa seu conforto, assim voc\u00ea n\u00e3o precisar\u00e1 preencher seus dados novamente quando fizer outro coment\u00e1rio. Estes cookies duram um ano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea tem uma conta e acessa este site, um cookie tempor\u00e1rio ser\u00e1 criado para determinar se seu navegador aceita cookies. Ele n\u00e3o cont\u00e9m nenhum dado pessoal e ser\u00e1 descartado quando voc\u00ea fechar seu navegador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando voc\u00ea acessa sua conta no site, tamb\u00e9m criamos v\u00e1rios cookies para salvar os dados da sua conta e suas escolhas de exibi\u00e7\u00e3o de tela. Cookies de login s\u00e3o mantidos por dois dias e cookies de op\u00e7\u00f5es de tela por um ano. Se voc\u00ea selecionar &#8220;Lembrar-me&#8221;, seu acesso ser\u00e1 mantido por duas semanas. Se voc\u00ea se desconectar da sua conta, os cookies de login ser\u00e3o removidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea editar ou publicar um artigo, um cookie adicional ser\u00e1 salvo no seu navegador. Este cookie n\u00e3o inclui nenhum dado pessoal e simplesmente indica o ID do post referente ao artigo que voc\u00ea acabou de editar. Ele expira depois de 1 dia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">M\u00eddia incorporada de outros sites<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Artigos neste site podem incluir conte\u00fado incorporado como, por exemplo, v\u00eddeos, imagens, artigos etc. Conte\u00fados incorporados de outros sites se comportam exatamente da mesma forma como se o visitante estivesse visitando o outro site.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estes sites podem coletar dados sobre voc\u00ea, usar cookies, incorporar rastreamento adicional de terceiros e monitorar sua intera\u00e7\u00e3o com este conte\u00fado incorporado, incluindo sua intera\u00e7\u00e3o com o conte\u00fado incorporado se voc\u00ea tem uma conta e est\u00e1 conectado com o site.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Com quem compartilhamos seus dados<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea solicitar uma redefini\u00e7\u00e3o de senha, seu endere\u00e7o de IP ser\u00e1 inclu\u00eddo no e-mail de redefini\u00e7\u00e3o de senha.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por quanto tempo mantemos os seus dados<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea deixar um coment\u00e1rio, o coment\u00e1rio e os seus metadados s\u00e3o conservados indefinidamente. Fazemos isso para que seja poss\u00edvel reconhecer e aprovar automaticamente qualquer coment\u00e1rio posterior ao inv\u00e9s de ret\u00ea-lo para modera\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para usu\u00e1rios que se registram no nosso site (se houver), tamb\u00e9m guardamos as informa\u00e7\u00f5es pessoais que fornecem no seu perfil de usu\u00e1rio. Todos os usu\u00e1rios podem ver, editar ou excluir suas informa\u00e7\u00f5es pessoais a qualquer momento (s\u00f3 n\u00e3o \u00e9 poss\u00edvel alterar o seu username). Os administradores de sites tamb\u00e9m podem ver e editar estas informa\u00e7\u00f5es.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quais os seus direitos sobre seus dados<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea tiver uma conta neste site ou se tiver deixado coment\u00e1rios, pode solicitar um arquivo exportado dos dados pessoais que mantemos sobre voc\u00ea, inclusive quaisquer dados que nos tenha fornecido. Tamb\u00e9m pode solicitar que removamos qualquer dado pessoal que mantemos sobre voc\u00ea. Isto n\u00e3o inclui nenhuns dados que somos obrigados a manter para prop\u00f3sitos administrativos, legais ou de seguran\u00e7a.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Para onde seus dados s\u00e3o enviados<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Coment\u00e1rios de visitantes podem ser marcados por um servi\u00e7o autom\u00e1tico de detec\u00e7\u00e3o de spam.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quem sou Sou a TCL Tech. O endere\u00e7o do site \u00e9: https:\/\/tcltech.com.br. Coment\u00e1rios Quando os visitantes deixam coment\u00e1rios no site, coletamos os dados mostrados no formul\u00e1rio de coment\u00e1rios, al\u00e9m do endere\u00e7o de IP e de dados do navegador do visitante, para auxiliar na detec\u00e7\u00e3o de spam. Uma sequ\u00eancia anonimizada de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tcltech.com.br\/index.php\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tcltech.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tcltech.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tcltech.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tcltech.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":1,"href":"https:\/\/tcltech.com.br\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":113,"href":"https:\/\/tcltech.com.br\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions\/113"}],"wp:attachment":[{"href":"https:\/\/tcltech.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}